{"id":2666,"date":"2026-04-08T12:05:40","date_gmt":"2026-04-08T11:05:40","guid":{"rendered":"https:\/\/staging.viajaenminibus.com\/?page_id=2666"},"modified":"2026-07-15T16:06:44","modified_gmt":"2026-07-15T15:06:44","slug":"contacto","status":"publish","type":"page","link":"https:\/\/viajaenminibus.com\/es\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"<style>.kb-row-layout-id2666_795256-01 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id2666_795256-01 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id2666_795256-01 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-none, 0rem );max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);min-height:480px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2666_795256-01{background-image:url('https:\/\/viajaenminibus.com\/wp-content\/uploads\/2026\/01\/autobus-viajaenminibus.webp');background-size:cover;background-position:center center;background-attachment:scroll;background-repeat:no-repeat;}.kb-row-layout-id2666_795256-01 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id2666_795256-01{z-index:9;position:relative;}@media all and (max-width: 1024px){.kb-row-layout-id2666_795256-01 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2666_795256-01 > .kt-row-column-wrap{min-height:325px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2666_795256-01 alignnone kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column2666_37dda6-47 > .kt-inside-inner-col{display:flex;}.kadence-column2666_37dda6-47 > .kt-inside-inner-col{min-height:0px;}.kadence-column2666_37dda6-47 > .kt-inside-inner-col,.kadence-column2666_37dda6-47 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2666_37dda6-47 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2666_37dda6-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}.kadence-column2666_37dda6-47 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column2666_37dda6-47 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column2666_37dda6-47 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column2666_37dda6-47{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_37dda6-47{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_37dda6-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column2666_37dda6-47 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2666_37dda6-47{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column2666_37dda6-47{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_37dda6-47{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_37dda6-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column2666_37dda6-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column2666_37dda6-47{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_37dda6-47{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_37dda6-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column2666_37dda6-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}.kadence-column2666_37dda6-47 {max-width: 1400px;}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2666_37dda6-47\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2666_91f7de-b7, .wp-block-kadence-advancedheading.kt-adv-heading2666_91f7de-b7[data-kb-block=\"kb-adv-heading2666_91f7de-b7\"]{max-width:100%;padding-bottom:0px;margin-bottom:0px;font-size:55px;line-height:3.5rem;font-weight:500;font-style:normal;font-family:Outfit;}.wp-block-kadence-advancedheading.kt-adv-heading2666_91f7de-b7 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2666_91f7de-b7[data-kb-block=\"kb-adv-heading2666_91f7de-b7\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2666_91f7de-b7 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2666_91f7de-b7[data-kb-block=\"kb-adv-heading2666_91f7de-b7\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading2666_91f7de-b7, .wp-block-kadence-advancedheading.kt-adv-heading2666_91f7de-b7[data-kb-block=\"kb-adv-heading2666_91f7de-b7\"]{max-width:100%;font-size:var(--global-kb-font-size-xl, 3rem);line-height:2.5rem;}}<\/style>\n<h1 class=\"kt-adv-heading2666_91f7de-b7 wp-block-kadence-advancedheading has-theme-palette-9-color has-text-color\" data-kb-block=\"kb-adv-heading2666_91f7de-b7\">Contacta con Nosotros: Estaremos encantados de asesorarte<\/h1>\n\n\n<nav aria-label=\"breadcrumbs\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Inicio<\/span><\/p><\/nav>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2666_5c04a2-6c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2666_5c04a2-6c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2666_5c04a2-6c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id2666_5c04a2-6c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2666_5c04a2-6c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id2666_5c04a2-6c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2666_5c04a2-6c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2666_af85fa-6d > .kt-inside-inner-col{display:flex;}.kadence-column2666_af85fa-6d > .kt-inside-inner-col,.kadence-column2666_af85fa-6d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2666_af85fa-6d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2666_af85fa-6d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column2666_af85fa-6d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column2666_af85fa-6d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_af85fa-6d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_af85fa-6d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column2666_af85fa-6d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2666_af85fa-6d{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column2666_af85fa-6d{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_af85fa-6d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_af85fa-6d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column2666_af85fa-6d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column2666_af85fa-6d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_af85fa-6d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_af85fa-6d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column2666_af85fa-6d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2666_af85fa-6d\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2666_62e2b5-2d, .wp-block-kadence-advancedheading.kt-adv-heading2666_62e2b5-2d[data-kb-block=\"kb-adv-heading2666_62e2b5-2d\"]{max-width:100%;padding-bottom:0px;margin-bottom:0px;font-weight:600;font-style:normal;font-family:Outfit;color:#505050;}.wp-block-kadence-advancedheading.kt-adv-heading2666_62e2b5-2d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2666_62e2b5-2d[data-kb-block=\"kb-adv-heading2666_62e2b5-2d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2666_62e2b5-2d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2666_62e2b5-2d[data-kb-block=\"kb-adv-heading2666_62e2b5-2d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading2666_62e2b5-2d, .wp-block-kadence-advancedheading.kt-adv-heading2666_62e2b5-2d[data-kb-block=\"kb-adv-heading2666_62e2b5-2d\"]{max-width:100%;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading2666_62e2b5-2d, .wp-block-kadence-advancedheading.kt-adv-heading2666_62e2b5-2d[data-kb-block=\"kb-adv-heading2666_62e2b5-2d\"]{max-width:100%;font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 class=\"kt-adv-heading2666_62e2b5-2d wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2666_62e2b5-2d\">Datos de contacto <\/h2>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-2666_744699-2f .kt-block-spacer{height:40px;}.wp-block-kadence-spacer.kt-block-spacer-2666_744699-2f .kt-divider{border-top-width:11px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:33%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-2666_744699-2f\"><div class=\"kt-block-spacer kt-block-spacer-halign-left\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items2666_048574-18:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items2666_048574-18 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;padding-top:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items2666_048574-18 ul.kt-svg-icon-list{grid-row-gap:15px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items2666_048574-18 .kb-svg-icon-wrap{color:var(--global-palette14, #3182CE);}.wp-block-kadence-iconlist.kt-svg-icon-list-items2666_048574-18 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items2666_048574-18 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items2666_048574-18 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-2666_1f2f80-22 .kt-svg-icon-list-single{color:var(--global-palette14, #3182CE) !important;}.kt-svg-icon-list-item-2666_1f2f80-22 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-2666_1f2f80-22\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_phone kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M22 16.92v3a2 2 0 0 1-2.18 2 19.79 19.79 0 0 1-8.63-3.07 19.5 19.5 0 0 1-6-6 19.79 19.79 0 0 1-3.07-8.67A2 2 0 0 1 4.11 2h3a2 2 0 0 1 2 1.72 12.84 12.84 0 0 0 .7 2.81 2 2 0 0 1-.45 2.11L8.09 9.91a16 16 0 0 0 6 6l1.27-1.27a2 2 0 0 1 2.11-.45 12.84 12.84 0 0 0 2.81.7A2 2 0 0 1 22 16.92z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"tel:(+34)952751426\">+34 952 751 426<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-2666_1a9539-48 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-2666_1a9539-48\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_smartphone kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"5\" y=\"2\" width=\"14\" height=\"20\" rx=\"2\" ry=\"2\"\/><line x1=\"12\" y1=\"18\" x2=\"12\" y2=\"18\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"tel:(+34)639171150\">+34 639 171 150<\/a><\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-2666_474411-83 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-2666_474411-83\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_mail kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M4 4h16c1.1 0 2 .9 2 2v12c0 1.1-.9 2-2 2H4c-1.1 0-2-.9-2-2V6c0-1.1.9-2 2-2z\"\/><polyline points=\"22,6 12,13 2,6\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\"><a href=\"mailto:comercial@viajaenminibus.com\">comercial@viajaenminibus.com<\/a><\/span><\/li>\n<\/ul><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column2666_775973-e6 > .kt-inside-inner-col{display:flex;}.kadence-column2666_775973-e6 > .kt-inside-inner-col,.kadence-column2666_775973-e6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2666_775973-e6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2666_775973-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column2666_775973-e6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column2666_775973-e6{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_775973-e6{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_775973-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column2666_775973-e6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2666_775973-e6{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column2666_775973-e6{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_775973-e6{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_775973-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column2666_775973-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column2666_775973-e6{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_775973-e6{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column2666_775973-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column2666_775973-e6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2666_775973-e6\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advanced-form4331-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form4331-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form4331-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form4331-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form4331-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form4331-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form4331-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form4331-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form4331-cpt-id .kb-advanced-form textarea{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;}<\/style><div class=\"wp-block-kadence-advanced-form wp-block-kadence-advanced-form4331-cpt-id kb-adv-form-label-style-normal kb-adv-form-input-size-standard kb-form-basic-style\"><form id=\"kb-adv-form-4331-cpt-id\" class=\"kb-advanced-form\" method=\"post\" data-kb-events=\"yes\">\n<style>.kb-row-layout-id4331_e687c4-8b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4331_e687c4-8b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4331_e687c4-8b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4331_e687c4-8b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4331_e687c4-8b > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4331_e687c4-8b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4331_e687c4-8b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4331_252148-d1 > .kt-inside-inner-col,.kadence-column4331_252148-d1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4331_252148-d1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4331_252148-d1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4331_252148-d1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4331_252148-d1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4331_252148-d1{position:relative;}@media all and (max-width: 1024px){.kadence-column4331_252148-d1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4331_252148-d1 > .kt-inside-inner-col{padding-bottom:0px;flex-direction:column;justify-content:center;}.kadence-column4331_252148-d1, .kt-inside-inner-col > .kadence-column4331_252148-d1:not(.specificity){margin-bottom:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4331_252148-d1\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field4331c6aa69-33 form-campo-nombre wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field4331c6aa69-33\">Nombre<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"fieldc6aa69-33\" id=\"field4331c6aa69-33\" data-label=\"Nombre\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field4331875384-44 wp-block-kadence-advanced-form-number\"><label class=\"kb-adv-form-label\" for=\"field4331875384-44\">Tel\u00e9fono<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"field875384-44\" id=\"field4331875384-44\" data-label=\"Tel\u00e9fono\" type=\"number\" placeholder=\"\" value=\"\" data-type=\"number\" class=\"kb-field kb-number-field\" data-required=\"yes\" required aria-required=\"true\" \/><\/div><\/div><\/div>\n\n\n<style>.kadence-column4331_0fa280-85 > .kt-inside-inner-col,.kadence-column4331_0fa280-85 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4331_0fa280-85 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4331_0fa280-85 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4331_0fa280-85 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4331_0fa280-85 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4331_0fa280-85{position:relative;}@media all and (max-width: 1024px){.kadence-column4331_0fa280-85 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4331_0fa280-85 > .kt-inside-inner-col{padding-bottom:0px;flex-direction:column;justify-content:center;}.kadence-column4331_0fa280-85, .kt-inside-inner-col > .kadence-column4331_0fa280-85:not(.specificity){margin-bottom:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4331_0fa280-85\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field43318f9875-6c form-campo-nombre wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field43318f9875-6c\">Apellidos<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"field8f9875-6c\" id=\"field43318f9875-6c\" data-label=\"Apellidos\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field43313c9e24-05 form-campo wp-block-kadence-advanced-form-email\"><label class=\"kb-adv-form-label\" for=\"field43313c9e24-05\">Email<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"field3c9e24-05\" id=\"field43313c9e24-05\" data-label=\"Email\" type=\"email\" placeholder=\"\" value=\"\" data-type=\"email\" class=\"kb-field kb-email-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field4331a075e6-db wp-block-kadence-advanced-form-textarea\"><textarea name=\"fielda075e6-db\" id=\"field4331a075e6-db\" rows=\"3\"  data-label=\"Message\" placeholder=\"Mensaje\" data-type=\"textarea\" class=\"kb-field kb-textarea-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Message\"><\/textarea><\/div>\n\n<div class=\"kb-adv-form-field kb-field4331d549be-25 wp-block-kadence-advanced-form-checkbox\"><fieldset class=\"kb-radio-check-item-wrap\" id=\"cb4331d549be-25\" data-type=\"checkbox\" data-required=\"yes\" ><div class=\"kb-radio-check-item\"><input class=\"kb-checkbox-style\" type=\"checkbox\"  id=\"field4331d549be-25_0\" name=\"fieldd549be-25[]\" value=\"Acepto la &lt;a href=&quot;https:\/\/viajaenminibus.com\/es\/declaracion-de-privacidad-ue\/&quot;&gt;Pol\u00edtica de privacidad&lt;\/a&gt;\"><label for=\"field4331d549be-25_0\">Acepto la <a href=\"https:\/\/viajaenminibus.com\/es\/declaracion-de-privacidad-ue\/\">Pol\u00edtica de privacidad<\/a><\/label><\/div><\/fieldset><\/div>\n\n<style>ul.menu .kb-submit-field .kb-btn977eda-57.kb-button{width:initial;}.kb-submit-field.kb-field977eda-57{justify-content:flex-start;}<\/style><div class=\"kb-adv-form-field kb-submit-field kb-field977eda-57 wp-block-kadence-advanced-form-submit\"><button class=\"kb-button kt-button button kb-adv-form-submit-button kb-btn977eda-57 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false\" type=\"submit\"><span class=\"kt-btn-inner-text\">Enviar<\/span><\/button><\/div>\n<input type=\"hidden\" name=\"_kb_adv_form_post_id\" value=\"4331\"><input type=\"hidden\" name=\"action\" value=\"kb_process_advanced_form_submit\"><input type=\"hidden\" name=\"_kb_adv_form_id\" value=\"4331-cpt-id\"><\/form><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2666_43ee80-5e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2666_43ee80-5e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2666_43ee80-5e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id2666_43ee80-5e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2666_43ee80-5e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id2666_43ee80-5e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2666_43ee80-5e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2666_3971a3-72 > .kt-inside-inner-col,.kadence-column2666_3971a3-72 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2666_3971a3-72 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2666_3971a3-72 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2666_3971a3-72 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2666_3971a3-72 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2666_3971a3-72{position:relative;}@media all and (max-width: 1024px){.kadence-column2666_3971a3-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2666_3971a3-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2666_3971a3-72\"><div class=\"kt-inside-inner-col\"><div class=\"wp-gr rpi\" data-id=\"2104\" data-layout=\"slider\" data-exec=\"false\" data-options='{&quot;text_size&quot;:&quot;&quot;,&quot;trans&quot;:{&quot;read more&quot;:&quot;leer m\\u00e1s&quot;}}'><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" style=\"display:none!important\"><symbol id=\"grw-tripadvisor\" viewBox=\"0 0 713.496 713.496\"><g><circle fill=\"#34E0A1\" cx=\"356.749\" cy=\"356.748\" r=\"356.748\"\/><path d=\"M577.095,287.152l43.049-46.836h-95.465c-47.792-32.646-105.51-51.659-167.931-51.659   c-62.342,0-119.899,19.054-167.612,51.659H93.432l43.049,46.836c-26.387,24.075-42.929,58.754-42.929,97.259   c0,72.665,58.914,131.578,131.579,131.578c34.519,0,65.968-13.313,89.446-35.077l42.172,45.919l42.172-45.879   c23.478,21.764,54.887,35.037,89.406,35.037c72.665,0,131.658-58.913,131.658-131.578   C620.024,345.866,603.483,311.188,577.095,287.152z M225.17,473.458c-49.188,0-89.047-39.859-89.047-89.047   s39.86-89.048,89.047-89.048c49.187,0,89.047,39.86,89.047,89.048S274.357,473.458,225.17,473.458z M356.788,381.82   c0-58.595-42.61-108.898-98.853-130.383c30.413-12.716,63.776-19.771,98.813-19.771s68.439,7.055,98.853,19.771   C399.399,272.962,356.788,323.226,356.788,381.82z M488.367,473.458c-49.188,0-89.048-39.859-89.048-89.047   s39.86-89.048,89.048-89.048s89.047,39.86,89.047,89.048S537.554,473.458,488.367,473.458z M488.367,337.694   c-25.79,0-46.677,20.887-46.677,46.677c0,25.789,20.887,46.676,46.677,46.676c25.789,0,46.676-20.887,46.676-46.676   C535.042,358.621,514.156,337.694,488.367,337.694z M271.846,384.411c0,25.789-20.887,46.676-46.676,46.676   s-46.676-20.887-46.676-46.676c0-25.79,20.887-46.677,46.676-46.677C250.959,337.694,271.846,358.621,271.846,384.411z\"\/><\/g><\/symbol><symbol id=\"grw-google\" viewBox=\"0 0 512 512\"><g fill=\"none\" fill-rule=\"evenodd\"><path d=\"M482.56 261.36c0-16.73-1.5-32.83-4.29-48.27H256v91.29h127.01c-5.47 29.5-22.1 54.49-47.09 71.23v59.21h76.27c44.63-41.09 70.37-101.59 70.37-173.46z\" fill=\"#4285f4\"\/><path d=\"M256 492c63.72 0 117.14-21.13 156.19-57.18l-76.27-59.21c-21.13 14.16-48.17 22.53-79.92 22.53-61.47 0-113.49-41.51-132.05-97.3H45.1v61.15c38.83 77.13 118.64 130.01 210.9 130.01z\" fill=\"#34a853\"\/><path d=\"M123.95 300.84c-4.72-14.16-7.4-29.29-7.4-44.84s2.68-30.68 7.4-44.84V150.01H45.1C29.12 181.87 20 217.92 20 256c0 38.08 9.12 74.13 25.1 105.99l78.85-61.15z\" fill=\"#fbbc05\"\/><path d=\"M256 113.86c34.65 0 65.76 11.91 90.22 35.29l67.69-67.69C373.03 43.39 319.61 20 256 20c-92.25 0-172.07 52.89-210.9 130.01l78.85 61.15c18.56-55.78 70.59-97.3 132.05-97.3z\" fill=\"#ea4335\"\/><path d=\"M20 20h472v472H20V20z\"\/><\/g><\/symbol><\/svg><div class=\"grw-row grw-row-m\" data-options='{&quot;speed&quot;:3,&quot;autoplay&quot;:true,&quot;mousestop&quot;:true,&quot;breakpoints&quot;:&quot;&quot;}'><div class=\"grw-header\"><div class=\"grw-header-inner rpi-flx rpi-row12\"><div class=\"grw-img-wrap\"><img decoding=\"async\" class=\"grw-img\" src=\"https:\/\/lh3.googleusercontent.com\/places\/ANXAkqHbgImVQ8H73mNyDjsFJ4EhyQvFNiB7ARHWHDalJd7nGc2gF6yoXPCYImPUuF-TVI5ABzXI6_mJi103fUZ9JRUNvVZw-qoBdA=s4800-w300-h300\" loading=\"lazy\" alt=\"VIAJAenMINIBUS.com place picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!=&#039;data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7&#039;)this.src=&#039;data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7&#039;;\" title=\"\"><\/div><div class=\"rpi-flx rpi-col8\"><div class=\"wp-google-name\"><a href=\"https:\/\/maps.google.com\/?cid=11971093398894102746&#038;g_mp=CiVnb29nbGUubWFwcy5wbGFjZXMudjEuUGxhY2VzLkdldFBsYWNlEAIYBCAA\" target=\"_blank\" rel=\"nofollow noopener\">VIAJAenMINIBUS.com<\/a><\/div><span class=\"rpi-stars\" style=\"--rating:4.9\">4.9<\/span><div class=\"wp-google-based\">Basado en 69 rese\u00f1as. <\/div><div class=\"wp-google-powered\">powered by <span><span style=\"color:#3c6df0!important\">G<\/span><span style=\"color:#d93025!important\">o<\/span><span style=\"color:#fb8e28!important\">o<\/span><span style=\"color:#3c6df0!important\">g<\/span><span style=\"color:#188038!important\">l<\/span><span style=\"color:#d93025!important\">e<\/span><\/span><\/div><div class=\"wp-google-wr\"><a href=\"https:\/\/search.google.com\/local\/writereview?placeid=ChIJP2p7zOP3cg0R2kgbTgXeIaY\" target=\"_blank\" rel=\"nofollow noopener\" onclick=\"return rplg_leave_review_window.call(this)\">val\u00f3ranos en<svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"><\/use><\/svg><\/a><\/div><\/div><\/div><\/div><div class=\"rpi-slides-root grw-content\"><div class=\"grw-content-inner\"><button class=\"rpi-ltgt rpi-lt grw-prev\" tabindex=\"0\"><\/button><div class=\"rpi-slides grw-reviews rpi-slides-bite\" data-count=\"5\" data-offset=\"5\"><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd grw-round\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img decoding=\"async\" class=\"grw-img\" src=\"https:\/\/viajaenminibus.com\/wp-content\/uploads\/2026\/01\/ChIJP2p7zOP3cg0R2kgbTgXeIaY_74d901b1f7d2440e90e72d6db9391b46.jpg\" loading=\"lazy\" alt=\"Beatriz Garc\u00eda A. profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!=&#039;https:\/\/viajaenminibus.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png&#039;)this.src=&#039;https:\/\/viajaenminibus.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png&#039;;\" title=\"\"><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/116121433762593799966\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Beatriz Garc\u00eda A.<\/a><div class=\"wp-google-time\" data-time=\"1760557383\">hace 9 meses<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">Contratamos los servicios de autob\u00fas para nuestra boda y sali\u00f3 todo perfectamente. Marco estuvo muy atento en todo momento y nos asesor\u00f3 con c\u00f3mo distribuir los autobuses y organizar el horario. No dudaremos en contar con \u00e9l para el futuro!<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd grw-round\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img decoding=\"async\" class=\"grw-img\" src=\"https:\/\/viajaenminibus.com\/wp-content\/uploads\/2026\/01\/ChIJP2p7zOP3cg0R2kgbTgXeIaY_cc70507c538fbfc885d193a1a7094b68.jpg\" loading=\"lazy\" alt=\"Alejandra T. profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!=&#039;https:\/\/viajaenminibus.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png&#039;)this.src=&#039;https:\/\/viajaenminibus.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png&#039;;\" title=\"\"><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/114096807480684913896\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Alejandra T.<\/a><div class=\"wp-google-time\" data-time=\"1754124234\">hace 12 meses<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">Queremos agradecer de coraz\u00f3n a Marco y a todo el equipo de Viaja en Minib\u00fas por el excelente servicio en nuestra boda. Desde el primer momento, Marco fue s\u00faper amable, nos ayud\u00f3 en todo y nos dio much\u00edsima tranquilidad. Los minibuses llegaron puntuales, s\u00faper limpios, y los conductores fueron muy profesionales. \u00a1Todo sali\u00f3 perfecto y nuestros invitados quedaron encantados!<br \/>Mil gracias por ser parte de un d\u00eda tan especial. \u00a1Recomendamos a Viaja en Minib\u00fas con los ojos cerrados!. &#x1f64c;&#x1f68d;&#x1f495;<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd grw-round\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img decoding=\"async\" class=\"grw-img\" src=\"https:\/\/viajaenminibus.com\/wp-content\/uploads\/2026\/01\/ChIJP2p7zOP3cg0R2kgbTgXeIaY_0681fb19956734b9ec22c12dc6b67b45.jpg\" loading=\"lazy\" alt=\"ecf profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!=&#039;https:\/\/viajaenminibus.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png&#039;)this.src=&#039;https:\/\/viajaenminibus.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png&#039;;\" title=\"\"><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/107664886888573252181\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">ecf<\/a><div class=\"wp-google-time\" data-time=\"1753706064\">hace 12 meses<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">Contratamos un viaje para una boda en Ja\u00e9n saliendo desde Antequera. Marcos siempre disponible y adapt\u00e1ndose a nuestras necesidades aconsej\u00e1ndonos lo mejor. El d\u00eda de la boda funcionaron estupendamente. Sin duda volver\u00e9 a contar con ellos si me hace falta.<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd grw-round\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img decoding=\"async\" class=\"grw-img\" src=\"https:\/\/viajaenminibus.com\/wp-content\/uploads\/2026\/01\/ChIJP2p7zOP3cg0R2kgbTgXeIaY_3ab9a3c1e4c51bacb1d1840ea5e57bbc.jpg\" loading=\"lazy\" alt=\"Julieta M. profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!=&#039;https:\/\/viajaenminibus.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png&#039;)this.src=&#039;https:\/\/viajaenminibus.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png&#039;;\" title=\"\"><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/102919148021169039752\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Julieta M.<\/a><div class=\"wp-google-time\" data-time=\"1753603639\">hace 12 meses<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">Muy recomendable. Lo contratamos para 2 dias una escapada de empresa e hicimos 6 viajes, los conductores son muy puntuales, simp\u00e1ticos, educados\u2026 los autobuses est\u00e1n cuidados y  limpios. Muy buena experiencia. Hicimos algunos viajes con Carlos y otros con otro conductor que no se el nombre pero un 10 para los dos. Muchas gracias, repetiremos.<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><div class=\"rpi-slide grw-review\"><div class=\"rpi-flx rpi-col12 grw-review-inner grw-backgnd grw-round\"><div class=\"rpi-flx rpi-row12-center\"><div class=\"grw-img-wrap\"><img decoding=\"async\" class=\"grw-img\" src=\"https:\/\/viajaenminibus.com\/wp-content\/uploads\/2026\/01\/ChIJP2p7zOP3cg0R2kgbTgXeIaY_8a16a43013205aaa098575367fd45e98.jpg\" loading=\"lazy\" alt=\"Andres Jesus Sanchez F. profile picture\" width=\"50\" height=\"50\" onerror=\"if(this.src!=&#039;https:\/\/viajaenminibus.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png&#039;)this.src=&#039;https:\/\/viajaenminibus.com\/wp-content\/plugins\/widget-google-reviews\/assets\/img\/guest.png&#039;;\" title=\"\"><\/div><div class=\"rpi-flx rpi-col6\"><a href=\"https:\/\/www.google.com\/maps\/contrib\/107658200018399895372\/reviews\" class=\"wp-google-name\" target=\"_blank\" rel=\"nofollow noopener\">Andres Jesus Sanchez F.<\/a><div class=\"wp-google-time\" data-time=\"1750750763\">hace 1 a\u00f1o<\/div><\/div><\/div><span class=\"rpi-stars\" style=\"--rating:5\"><\/span><div class=\"rpi-flx rpi-col4\"><div class=\"wp-google-feedback grw-scroll\" ><span class=\"wp-google-text\">El servicio de Marco (Viajaenminibus) para nuestra boda fue simplemente incre\u00edble. Desde el primer momento, s\u00faper cercano, atento y dispuesto a facilitarnos todo. El mejor precio que encontramos y encima con una atenci\u00f3n de diez. Los autobuses fueron c\u00f3modos, puntuales y todos los invitados quedaron encantados. \u00a1Un acierto total y 100% recomendable!<\/span><\/div><\/div><svg height=\"16\" width=\"16\" role=\"none\"><use href=\"#grw-google\"\/><\/svg><\/div><\/div><\/div><button class=\"rpi-ltgt rpi-gt grw-next\" tabindex=\"0\"><\/button><div class=\"rpi-dots-wrap\"><div class=\"rpi-dots\"><\/div><\/div><\/div><\/div><\/div><script>(function(p){if(!p)return;let w=p.offsetWidth,m=function(a,b){return Math.min(a,b)===a};p.querySelector('.grw-row').classList.replace('grw-row-m','grw-row-'+(m(w,510)?'xs':m(w,750)?'x':m(w,1100)?'s':m(w,1450)?'m':m(w,1800)?'l':'xl'))})(document.currentScript?.parentElement)<\/script><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id2666_79bd9e-82 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id2666_79bd9e-82 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id2666_79bd9e-82 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1400px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id2666_79bd9e-82 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id2666_79bd9e-82 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id2666_79bd9e-82 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id2666_79bd9e-82 alignnone has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column2666_1318ce-1e > .kt-inside-inner-col,.kadence-column2666_1318ce-1e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2666_1318ce-1e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2666_1318ce-1e > .kt-inside-inner-col{flex-direction:column;}.kadence-column2666_1318ce-1e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2666_1318ce-1e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2666_1318ce-1e{position:relative;}@media all and (max-width: 1024px){.kadence-column2666_1318ce-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2666_1318ce-1e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2666_1318ce-1e\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2666_d46a20-d8, .wp-block-kadence-advancedheading.kt-adv-heading2666_d46a20-d8[data-kb-block=\"kb-adv-heading2666_d46a20-d8\"]{display:block;font-size:42px;line-height:35px;font-style:normal;color:#505050;}.wp-block-kadence-advancedheading.kt-adv-heading2666_d46a20-d8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2666_d46a20-d8[data-kb-block=\"kb-adv-heading2666_d46a20-d8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2666_d46a20-d8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2666_d46a20-d8[data-kb-block=\"kb-adv-heading2666_d46a20-d8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<span class=\"kt-adv-heading2666_d46a20-d8 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2666_d46a20-d8\">Informaci\u00f3n adicional<\/span>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-2666_88f966-96 .kt-block-spacer{height:40px;}.wp-block-kadence-spacer.kt-block-spacer-2666_88f966-96 .kt-divider{border-top-width:11px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:42%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-2666_88f966-96\"><div class=\"kt-block-spacer kt-block-spacer-halign-left\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kadence-column2666_5fce71-6e > .kt-inside-inner-col,.kadence-column2666_5fce71-6e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2666_5fce71-6e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2666_5fce71-6e > .kt-inside-inner-col{flex-direction:column;}.kadence-column2666_5fce71-6e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2666_5fce71-6e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2666_5fce71-6e{position:relative;}@media all and (max-width: 1024px){.kadence-column2666_5fce71-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2666_5fce71-6e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2666_5fce71-6e\"><div class=\"kt-inside-inner-col\"><style>.kb-block-show-more-container2666_248e64-a8 > .kb-show-more-sr-excerpt{position:absolute;width:1px;height:1px;margin:-1px;overflow:hidden;clip:rect(0, 0, 0, 0);white-space:nowrap;}.kb-block-show-more-container2666_248e64-a8 > .wp-block-kadence-advancedbtn{margin-top:1em;}.kb-block-show-more-container2666_248e64-a8 > .wp-block-kadence-advancedbtn .kt-btn-wrap:nth-child(2), .kb-block-show-more-container2666_248e64-a8 > .wp-block-kadence-advancedbtn .wp-block-kadence-singlebtn:nth-of-type(2){display:none;}.kb-block-show-more-container2666_248e64-a8 > .wp-block-kadence-column{max-height:275px;overflow-y:hidden;-webkit-mask-image:linear-gradient(to bottom, black 50%, transparent 100%);mask-image:linear-gradient(to bottom, black 50%, transparent 100%);}.kb-block-show-more-container2666_248e64-a8.kb-smc-open > .wp-block-kadence-column{max-height:none;-webkit-mask-image:none;mask-image:none;overflow-y:unset;}.kb-block-show-more-container2666_248e64-a8.kb-smc-open > .wp-block-kadence-advancedbtn .kt-btn-wrap:nth-child(1), .kb-block-show-more-container2666_248e64-a8.kb-smc-open > .wp-block-kadence-advancedbtn .wp-block-kadence-singlebtn:nth-of-type(1){display:none;}.kb-block-show-more-container2666_248e64-a8.kb-smc-open > .wp-block-kadence-advancedbtn .kt-btn-wrap:nth-child(2), .kb-block-show-more-container2666_248e64-a8.kb-smc-open > .wp-block-kadence-advancedbtn .wp-block-kadence-singlebtn:nth-of-type(2){display:inline-flex;}.kb-block-show-more-container2666_248e64-a8.kb-smc-open > .wp-block-kadence-advancedbtn.kt-force-btn-fullwidth .kt-btn-wrap:nth-child(2){display:block;}<\/style>\n<div class=\"wp-block-kadence-show-more kb-block-show-more-container kb-block-show-more-container2666_248e64-a8\"><div class=\"kb-show-more-sr-excerpt\" aria-live=\"polite\" aria-atomic=\"true\"><\/div><style>.kadence-column2666_80b82d-fb > .kt-inside-inner-col,.kadence-column2666_80b82d-fb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2666_80b82d-fb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2666_80b82d-fb > .kt-inside-inner-col{flex-direction:column;}.kadence-column2666_80b82d-fb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2666_80b82d-fb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2666_80b82d-fb{position:relative;}@media all and (max-width: 1024px){.kadence-column2666_80b82d-fb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2666_80b82d-fb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2666_80b82d-fb kb-show-more-content\"><div class=\"kt-inside-inner-col\">\n<p class=\"wp-block-paragraph\">Estamos aqu\u00ed para ayudaros a organizar vuestro transporte de grupos sin complicaciones. Tanto si ten\u00e9is claro lo que necesit\u00e1is como si a\u00fan est\u00e1is valorando opciones, podemos asesoraros sin ning\u00fan compromiso: os contamos qu\u00e9 veh\u00edculo se adapta mejor a vuestro grupo, qu\u00e9 opciones de ruta son m\u00e1s eficientes y cu\u00e1l ser\u00eda el coste aproximado del servicio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para solicitar presupuesto pod\u00e9is usar el formulario de esta p\u00e1gina, escribirnos a comercial@viajaenminibus.com o llamarnos directamente al 952 751 426 o al 639 171 150. Cuantos m\u00e1s detalles nos facilit\u00e9is sobre el servicio (n\u00famero de personas, puntos de recogida y destino, fecha y horario aproximado), m\u00e1s ajustado y r\u00e1pido ser\u00e1 el presupuesto que os preparemos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Respondemos todas las consultas con la mayor agilidad posible. Para bodas o eventos en fechas de alta demanda, os recomendamos contactarnos con bastante antelaci\u00f3n para asegurar la disponibilidad de la flota. Os garantizamos una atenci\u00f3n directa, sin intermediarios y con toda la informaci\u00f3n necesaria para que pod\u00e1is tomar la mejor decisi\u00f3n.<\/p>\n<\/div><\/div>\n\n\n<style>.wp-block-kadence-advancedbtn.kb-btnsbutton-one-1{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:flex-start;align-items:center;}.kt-btnsbutton-one-1 .kt-button{font-weight:normal;font-style:normal;}.kt-btnsbutton-one-1 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btnsbutton-one-1 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btnsbutton-one-1 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btnsbutton-one-1 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btnsbutton-one-1 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btnsbutton-one-1 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btnsbutton-one-1 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btnsbutton-one-1 kb-show-more-buttons\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn2666_382c97-03.kb-button{width:initial;}<\/style><button class=\"kb-button kt-button button kb-btn2666_382c97-03 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Mostrar m\u00e1s<\/span><\/button>\n\n<style>ul.menu .wp-block-kadence-advancedbtn .kb-btn2666_d9e574-07.kb-button{width:initial;}<\/style><button class=\"kb-button kt-button button kb-btn2666_d9e574-07 kt-btn-size-small kt-btn-width-type-auto kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false wp-block-kadence-singlebtn\"><span class=\"kt-btn-inner-text\">Mostrar menos<\/span><\/button><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column2666_f4c8ab-67 > .kt-inside-inner-col,.kadence-column2666_f4c8ab-67 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column2666_f4c8ab-67 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column2666_f4c8ab-67 > .kt-inside-inner-col{flex-direction:column;}.kadence-column2666_f4c8ab-67 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column2666_f4c8ab-67 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column2666_f4c8ab-67{position:relative;}@media all and (max-width: 1024px){.kadence-column2666_f4c8ab-67 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column2666_f4c8ab-67 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column2666_f4c8ab-67\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading2666_dab8d0-98, .wp-block-kadence-advancedheading.kt-adv-heading2666_dab8d0-98[data-kb-block=\"kb-adv-heading2666_dab8d0-98\"]{display:block;font-size:42px;line-height:35px;font-style:normal;color:#505050;}.wp-block-kadence-advancedheading.kt-adv-heading2666_dab8d0-98 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading2666_dab8d0-98[data-kb-block=\"kb-adv-heading2666_dab8d0-98\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading2666_dab8d0-98 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading2666_dab8d0-98[data-kb-block=\"kb-adv-heading2666_dab8d0-98\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<span class=\"kt-adv-heading2666_dab8d0-98 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading2666_dab8d0-98\">Preguntas frecuentes<\/span>\n\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-2666_252589-23 .kt-block-spacer{height:40px;}.wp-block-kadence-spacer.kt-block-spacer-2666_252589-23 .kt-divider{border-top-width:11px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:42%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-2666_252589-23\"><div class=\"kt-block-spacer kt-block-spacer-halign-left\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block bloque-faqs\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1766250403754\" class=\"rank-math-list-item\">\n<p class=\"rank-math-question \">\u00bfC\u00f3mo pido un presupuesto de transporte?<\/p>\n<div class=\"rank-math-answer \">\n\n<p>Pod\u00e9is rellenar el formulario de esta p\u00e1gina, llamarnos al 952 751 426 o al 639 171 150, o escribirnos a comercial@viajaenminibus.com. Cuantos m\u00e1s detalles nos deis sobre el servicio (n\u00famero de personas, origen, destino, fecha y horario), m\u00e1s r\u00e1pido y preciso ser\u00e1 el presupuesto.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1766250428872\" class=\"rank-math-list-item\">\n<p class=\"rank-math-question \">\u00bfEn qu\u00e9 horario podemos contactar?<\/p>\n<div class=\"rank-math-answer \">\n\n<p>Atendemos consultas de lunes a viernes en horario de oficina. Para servicios urgentes o consultas fuera de ese horario, pod\u00e9is llamarnos al 639 171 150 y os atendemos en la mayor brevedad posible.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1766250441273\" class=\"rank-math-list-item\">\n<p class=\"rank-math-question \">\u00bfCu\u00e1nto tard\u00e1is en responder a una solicitud?<\/p>\n<div class=\"rank-math-answer \">\n\n<p>Normalmente respondemos en pocas horas durante d\u00edas laborables. Si el formulario se env\u00eda por la tarde o en fin de semana, lo gestionamos el primer d\u00eda h\u00e1bil siguiente. Para fechas muy demandadas como bodas en temporada alta, os recomendamos contactarnos con antelaci\u00f3n.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>#kt-modal2134_e95c50-95 .kt-blocks-modal-link{color:#555555;background:transparent;border-color:#555555;border-radius:4px;font-size:16px;line-height:24px;border-width:2px 2px 2px 2px;padding:4px 8px 4px 8px;margin:0px 0px 0px 0px;}#kt-modal2134_e95c50-95 .kt-blocks-modal-link:hover, #kt-modal2134_e95c50-95 .kt-blocks-modal-link:focus{color:#ffffff;background:#444444;border-color:#444444;}#kt-modal2134_e95c50-95 .kt-modal-overlay, #kt-target-modal2134_e95c50-95 .kt-modal-overlay, .kb-modal-content2134_e95c50-95 .kt-modal-overlay{background:rgba(0, 0, 0, 0.6);}#kt-modal2134_e95c50-95 .kt-modal-overlay, #kt-target-modal2134_e95c50-95 .kt-modal-overlay, .kb-modal-content2134_e95c50-95 .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal2134_e95c50-95 .kt-modal-container, #kt-target-modal2134_e95c50-95 .kt-modal-container, .kb-modal-content2134_e95c50-95 .kt-modal-container{width:60%;max-width:1400px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:center;align-items:center;}#kt-modal2134_e95c50-95 .kt-modal-container, #kt-target-modal2134_e95c50-95 .kt-modal-container, .kb-modal-content2134_e95c50-95 .kt-modal-container{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}#kt-modal2134_e95c50-95 .kt-modal-container, #kt-target-modal2134_e95c50-95 .kt-modal-container, .kb-modal-content2134_e95c50-95 .kt-modal-container{background:#ffffff;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal2134_e95c50-95 .kt-modal-close svg, #kt-target-modal2134_e95c50-95 .kt-modal-close svg, .kb-modal-content2134_e95c50-95 .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal2134_e95c50-95 .kt-modal-container, #kt-target-modal2134_e95c50-95 .kt-modal-container, .kb-modal-content2134_e95c50-95 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}}@media all and (max-width: 1024px){#kt-modal2134_e95c50-95 .kt-modal-close svg, #kt-target-modal2134_e95c50-95 .kt-modal-close svg, .kb-modal-content2134_e95c50-95 .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal2134_e95c50-95 .kt-modal-container, #kt-target-modal2134_e95c50-95 .kt-modal-container, .kb-modal-content2134_e95c50-95 .kt-modal-container{width:100%;border-top:0px solid #ffffff;border-right:0px solid #ffffff;border-bottom:0px solid #ffffff;border-left:0px solid #ffffff;}#kt-modal2134_e95c50-95 .kt-modal-close svg, #kt-target-modal2134_e95c50-95 .kt-modal-close svg, .kb-modal-content2134_e95c50-95 .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignnone kt-modal-linkalign-center modal-bloque\" id=\"kt-modal2134_e95c50-95\"><div id=\"presupuesto-modal\" class=\"kb-modal-content2134_e95c50-95 kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal2134_e95c50-95-content\" class=\"kt-modal-content\"><style>.wp-block-kadence-advanced-form4185-cpt-id, .wp-block-kadence-advanced-form4185-cpt-id.kb-form-has-background{margin-top:var(--global-kb-spacing-xs, 1rem);margin-right:var(--global-kb-spacing-lg, 3rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);margin-left:var(--global-kb-spacing-lg, 3rem);}.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form textarea{border-top:1px solid #b9b9c5;border-right:1px solid #b9b9c5;border-bottom:1px solid #b9b9c5;border-left:1px solid #b9b9c5;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:10px;border-bottom-left-radius:10px;box-shadow:1px 1px 0px 0px rgba(0, 0, 0, 0.2);}.wp-block-kadence-advanced-form4185-cpt-id{--kb-form-border-width:1px;--kb-form-border-color:#b9b9c5;}.wp-block-kadence-advanced-form4185-cpt-id input[type=text]:focus,.wp-block-kadence-advanced-form4185-cpt-id input[type=email]:focus,.wp-block-kadence-advanced-form4185-cpt-id input[type=tel]:focus,.wp-block-kadence-advanced-form4185-cpt-id input[type=date]:focus,.wp-block-kadence-advanced-form4185-cpt-id input[type=number]:focus,.wp-block-kadence-advanced-form4185-cpt-id input[type=time]:focus,.wp-block-kadence-advanced-form4185-cpt-id input[type=file]:focus,.wp-block-kadence-advanced-form4185-cpt-id select:focus,.wp-block-kadence-advanced-form4185-cpt-id textarea:focus{border-color:var(--global-palette1);box-shadow:2px 2px 0px 0px rgba(0, 0, 0, 0.4);}.wp-block-kadence-advanced-form4185-cpt-id .kb-adv-form-field .kb-adv-form-label{color:var(--global-palette3, #1A202C);}@media all and (max-width: 1024px){.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form textarea{border-top:1px solid #b9b9c5;border-right:1px solid #b9b9c5;border-bottom:1px solid #b9b9c5;border-left:1px solid #b9b9c5;}}@media all and (max-width: 767px){.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=text],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=tel],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=number],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=date],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=time],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=email],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form input[type=file],.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form select,.wp-block-kadence-advanced-form4185-cpt-id .kb-advanced-form textarea{border-top:1px solid #b9b9c5;border-right:1px solid #b9b9c5;border-bottom:1px solid #b9b9c5;border-left:1px solid #b9b9c5;}}<\/style><div class=\"wp-block-kadence-advanced-form wp-block-kadence-advanced-form4185-cpt-id kb-adv-form-label-style-float kb-adv-form-input-size-small kb-form-basic-style\"><form id=\"kb-adv-form-4185-cpt-id\" class=\"kb-advanced-form\" method=\"post\" data-kb-events=\"yes\">\n<style>.kb-row-layout-id4185_5f2b47-40 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4185_5f2b47-40 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4185_5f2b47-40 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4185_5f2b47-40 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4185_5f2b47-40 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4185_5f2b47-40 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4185_5f2b47-40 alignnone cols-mov-form wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4185_035ffb-4a > .kt-inside-inner-col,.kadence-column4185_035ffb-4a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4185_035ffb-4a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4185_035ffb-4a > .kt-inside-inner-col{flex-direction:column;}.kadence-column4185_035ffb-4a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4185_035ffb-4a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4185_035ffb-4a{position:relative;}@media all and (max-width: 1024px){.kadence-column4185_035ffb-4a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4185_035ffb-4a > .kt-inside-inner-col{padding-bottom:0px;flex-direction:column;justify-content:center;}.kadence-column4185_035ffb-4a, .kt-inside-inner-col > .kadence-column4185_035ffb-4a:not(.specificity){margin-bottom:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4185_035ffb-4a\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field4185c6aa69-33 form-campo-nombre wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field4185c6aa69-33\">Nombre y apellidos<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"fieldc6aa69-33\" id=\"field4185c6aa69-33\" data-label=\"Nombre y apellidos\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field4185875384-44 wp-block-kadence-advanced-form-number\"><label class=\"kb-adv-form-label\" for=\"field4185875384-44\">Tel\u00e9fono<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"field875384-44\" id=\"field4185875384-44\" data-label=\"Tel\u00e9fono\" type=\"number\" placeholder=\"\" value=\"\" data-type=\"number\" class=\"kb-field kb-number-field\" data-required=\"yes\" required aria-required=\"true\" \/><\/div><\/div><\/div>\n\n\n<style>.kadence-column4185_969719-60 > .kt-inside-inner-col,.kadence-column4185_969719-60 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4185_969719-60 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4185_969719-60 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4185_969719-60 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4185_969719-60 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4185_969719-60{position:relative;}@media all and (max-width: 1024px){.kadence-column4185_969719-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4185_969719-60 > .kt-inside-inner-col{padding-bottom:0px;flex-direction:column;justify-content:center;}.kadence-column4185_969719-60, .kt-inside-inner-col > .kadence-column4185_969719-60:not(.specificity){margin-bottom:0px;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4185_969719-60\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field41853c9e24-05 form-campo wp-block-kadence-advanced-form-email\"><label class=\"kb-adv-form-label\" for=\"field41853c9e24-05\">Email<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"field3c9e24-05\" id=\"field41853c9e24-05\" data-label=\"Email\" type=\"email\" placeholder=\"\" value=\"\" data-type=\"email\" class=\"kb-field kb-email-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-infield-type-input kb-field4185611779-00 wp-block-kadence-advanced-form-select\"><label class=\"kb-adv-form-label\" for=\"field4185611779-00\">\u00bfEres empresa?<span class=\"kb-adv-form-required\">*<\/span><\/label><select  name=\"field611779-00\" id=\"field4185611779-00\" required aria-required=\"true\"><option value=\"No\" selected>No<\/option><option value=\"Si\">Si<\/option><\/select><\/div><\/div><\/div>\n\n\n<style>.kadence-column4185_50f730-bd > .kt-inside-inner-col{padding-top:0px;}.kadence-column4185_50f730-bd > .kt-inside-inner-col,.kadence-column4185_50f730-bd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4185_50f730-bd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4185_50f730-bd > .kt-inside-inner-col{flex-direction:column;}.kadence-column4185_50f730-bd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4185_50f730-bd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4185_50f730-bd{position:relative;}.kadence-column4185_50f730-bd, .kt-inside-inner-col > .kadence-column4185_50f730-bd:not(.specificity){margin-top:0px;}@media all and (max-width: 1024px){.kadence-column4185_50f730-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4185_50f730-bd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4185_50f730-bd\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field4185438815-5b wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field4185438815-5b\">Empresa<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"field438815-5b\" id=\"field4185438815-5b\" data-label=\"Empresa\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\" data-conditional-rules=\"{&quot;container&quot;:&quot;.kb-field4185438815-5b&quot;,&quot;action&quot;:&quot;show&quot;,&quot;logic&quot;:&quot;or&quot;,&quot;rules&quot;:[{&quot;name&quot;:&quot;field4185611779-00&quot;,&quot;operator&quot;:&quot;is&quot;,&quot;value&quot;:&quot;Si&quot;}]}\" \/><\/div><\/div><\/div>\n\n\n<style>.kadence-column4185_238e08-1f > .kt-inside-inner-col{padding-top:0px;}.kadence-column4185_238e08-1f > .kt-inside-inner-col,.kadence-column4185_238e08-1f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4185_238e08-1f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4185_238e08-1f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4185_238e08-1f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4185_238e08-1f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4185_238e08-1f{position:relative;}.kadence-column4185_238e08-1f, .kt-inside-inner-col > .kadence-column4185_238e08-1f:not(.specificity){margin-top:0px;}@media all and (max-width: 1024px){.kadence-column4185_238e08-1f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4185_238e08-1f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4185_238e08-1f\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field4185ab4013-1e wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field4185ab4013-1e\">CIF<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"fieldab4013-1e\" id=\"field4185ab4013-1e\" data-label=\"CIF\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\" data-conditional-rules=\"{&quot;container&quot;:&quot;.kb-field4185ab4013-1e&quot;,&quot;action&quot;:&quot;show&quot;,&quot;logic&quot;:&quot;or&quot;,&quot;rules&quot;:[{&quot;name&quot;:&quot;field4185611779-00&quot;,&quot;operator&quot;:&quot;is&quot;,&quot;value&quot;:&quot;Si&quot;}]}\" \/><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field4185f55617-5c wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field4185f55617-5c\">Direcci\u00f3n<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"fieldf55617-5c\" id=\"field4185f55617-5c\" data-label=\"Direcci\u00f3n\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"yes\" required aria-required=\"true\" data-conditional-rules=\"{&quot;container&quot;:&quot;.kb-field4185f55617-5c&quot;,&quot;action&quot;:&quot;show&quot;,&quot;logic&quot;:&quot;or&quot;,&quot;rules&quot;:[{&quot;name&quot;:&quot;field4185611779-00&quot;,&quot;operator&quot;:&quot;is&quot;,&quot;value&quot;:&quot;Si&quot;}]}\" \/><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-4185_b2fc9f-c2 .kt-block-spacer{height:25px;}.wp-block-kadence-spacer.kt-block-spacer-4185_b2fc9f-c2 .kt-divider{border-top-width:1px;height:1px;border-top-color:var(--global-palette1, #3182CE);width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-4185_b2fc9f-c2\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-id4185_a9a01e-9c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4185_a9a01e-9c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4185_a9a01e-9c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4185_a9a01e-9c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4185_a9a01e-9c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4185_a9a01e-9c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-sm, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4185_a9a01e-9c alignnone cols-mov-form wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4185_9216a2-05 > .kt-inside-inner-col,.kadence-column4185_9216a2-05 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4185_9216a2-05 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4185_9216a2-05 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4185_9216a2-05 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4185_9216a2-05 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4185_9216a2-05{position:relative;}@media all and (max-width: 1024px){.kadence-column4185_9216a2-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4185_9216a2-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4185_9216a2-05\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-infield-type-input kb-field4185bc59b0-f0 tipo-servicio wp-block-kadence-advanced-form-select\"><label class=\"kb-adv-form-label\" for=\"field4185bc59b0-f0\">Tipo de servicio<\/label><select  name=\"fieldbc59b0-f0\" id=\"field4185bc59b0-f0\" ><option value=\"Bodas\">Bodas<\/option><option value=\"Transfer aeropuerto\">Transfer aeropuerto<\/option><option value=\"Traslados\">Traslados<\/option><option value=\"Excursiones\">Excursiones<\/option><option value=\"Transporte empresarial\">Transporte empresarial<\/option><option value=\"Congresos y eventos\">Congresos y eventos<\/option><option value=\"VIP\">VIP<\/option><option value=\"Otros\">Otros<\/option><\/select><\/div>\n\n<style>.kb-row-layout-id4185_514ed8-c6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4185_514ed8-c6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4185_514ed8-c6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4185_514ed8-c6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4185_514ed8-c6 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4185_514ed8-c6 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4185_514ed8-c6 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-top\">\n<style>.kadence-column4185_15db31-0d > .kt-inside-inner-col,.kadence-column4185_15db31-0d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4185_15db31-0d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4185_15db31-0d > .kt-inside-inner-col{flex-direction:column;}.kadence-column4185_15db31-0d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4185_15db31-0d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4185_15db31-0d{position:relative;}@media all and (max-width: 1024px){.kadence-column4185_15db31-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4185_15db31-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4185_15db31-0d\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-infield-type-input kb-field4185409f72-02 wp-block-kadence-advanced-form-date\"><label class=\"kb-adv-form-label\" for=\"field4185409f72-02\">Fecha de ida<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"field409f72-02\" id=\"field4185409f72-02\" data-label=\"Fecha de ida\" type=\"date\" value=\"\" data-type=\"date\" class=\"kb-field kb-date-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div><\/div><\/div>\n\n\n<style>.kadence-column4185_451261-b2 > .kt-inside-inner-col,.kadence-column4185_451261-b2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4185_451261-b2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4185_451261-b2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4185_451261-b2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4185_451261-b2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4185_451261-b2{position:relative;}@media all and (max-width: 1024px){.kadence-column4185_451261-b2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4185_451261-b2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4185_451261-b2\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-infield-type-input kb-field4185012367-22 wp-block-kadence-advanced-form-time\"><label class=\"kb-adv-form-label\" for=\"field4185012367-22\">Hora de ida<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"field012367-22\" id=\"field4185012367-22\" data-label=\"Hora de ida\" type=\"time\" value=\"\" data-type=\"time\" class=\"kb-field kb-time-field\" data-required=\"yes\" required aria-required=\"true\"\/><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field41856ea28f-c2 wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field41856ea28f-c2\">Origen<\/label><input name=\"field6ea28f-c2\" id=\"field41856ea28f-c2\" data-label=\"Origen\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"no\" \/><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field4185f72e35-0e form-campo wp-block-kadence-advanced-form-number\"><label class=\"kb-adv-form-label\" for=\"field4185f72e35-0e\">N\u00famero de pasajeros<span class=\"kb-adv-form-required\">*<\/span><\/label><input name=\"fieldf72e35-0e\" id=\"field4185f72e35-0e\" data-label=\"N\u00famero de pasajeros\" type=\"number\" placeholder=\"\" value=\"\" data-type=\"number\" class=\"kb-field kb-number-field\" data-required=\"yes\" required aria-required=\"true\" \/><\/div><\/div><\/div>\n\n\n<style>.kadence-column4185_d41601-99 > .kt-inside-inner-col,.kadence-column4185_d41601-99 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4185_d41601-99 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4185_d41601-99 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4185_d41601-99 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4185_d41601-99 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4185_d41601-99{position:relative;}@media all and (max-width: 1024px){.kadence-column4185_d41601-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4185_d41601-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4185_d41601-99\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-infield-type-input kb-field41855d4aab-1f tipo-viaje wp-block-kadence-advanced-form-select\"><label class=\"kb-adv-form-label\" for=\"field41855d4aab-1f\">Tipo de viaje<span class=\"kb-adv-form-required\">*<\/span><\/label><select  name=\"field5d4aab-1f\" id=\"field41855d4aab-1f\" required aria-required=\"true\"><option value=\"Ida y vuelta\">Ida y vuelta<\/option><option value=\"Ida\">Ida<\/option><option value=\"A disposici\u00f3n\">A disposici\u00f3n<\/option><\/select><\/div>\n\n<style>.kb-row-layout-id4185_e5c267-f6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4185_e5c267-f6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4185_e5c267-f6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4185_e5c267-f6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4185_e5c267-f6 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4185_e5c267-f6 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4185_e5c267-f6 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-equal kt-row-valign-top\">\n<style>.kadence-column4185_b41b34-b6 > .kt-inside-inner-col,.kadence-column4185_b41b34-b6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4185_b41b34-b6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4185_b41b34-b6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4185_b41b34-b6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4185_b41b34-b6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4185_b41b34-b6{position:relative;}@media all and (max-width: 1024px){.kadence-column4185_b41b34-b6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4185_b41b34-b6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4185_b41b34-b6\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-infield-type-input kb-field41859dce71-3e wp-block-kadence-advanced-form-date\"><label class=\"kb-adv-form-label\" for=\"field41859dce71-3e\">Fecha de la vuelta<\/label><input name=\"field9dce71-3e\" id=\"field41859dce71-3e\" data-label=\"Fecha de la vuelta\" type=\"date\" value=\"\" data-type=\"date\" class=\"kb-field kb-date-field\" data-required=\"no\"  data-conditional-rules=\"{&quot;container&quot;:&quot;.kb-field41859dce71-3e&quot;,&quot;action&quot;:&quot;hide&quot;,&quot;logic&quot;:&quot;or&quot;,&quot;rules&quot;:[{&quot;name&quot;:&quot;field41855d4aab-1f&quot;,&quot;operator&quot;:&quot;is&quot;,&quot;value&quot;:&quot;Ida&quot;}]}\" \/><\/div><\/div><\/div>\n\n\n<style>.kadence-column4185_c8929c-19 > .kt-inside-inner-col,.kadence-column4185_c8929c-19 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4185_c8929c-19 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4185_c8929c-19 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4185_c8929c-19 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4185_c8929c-19 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4185_c8929c-19{position:relative;}@media all and (max-width: 1024px){.kadence-column4185_c8929c-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4185_c8929c-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4185_c8929c-19\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-adv-form-infield-type-input kb-field41852d3be7-ff wp-block-kadence-advanced-form-time\"><label class=\"kb-adv-form-label\" for=\"field41852d3be7-ff\">Hora de la vuelta<\/label><input name=\"field2d3be7-ff\" id=\"field41852d3be7-ff\" data-label=\"Hora de la vuelta\" type=\"time\" value=\"\" data-type=\"time\" class=\"kb-field kb-time-field\" data-required=\"no\"  data-conditional-rules=\"{&quot;container&quot;:&quot;.kb-field41852d3be7-ff&quot;,&quot;action&quot;:&quot;hide&quot;,&quot;logic&quot;:&quot;or&quot;,&quot;rules&quot;:[{&quot;name&quot;:&quot;field41855d4aab-1f&quot;,&quot;operator&quot;:&quot;is&quot;,&quot;value&quot;:&quot;Ida&quot;}]}\" \/><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field418564e034-b1 wp-block-kadence-advanced-form-text\"><label class=\"kb-adv-form-label\" for=\"field418564e034-b1\">Destino<\/label><input name=\"field64e034-b1\" id=\"field418564e034-b1\" data-label=\"Destino\" type=\"text\" placeholder=\"\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-field\" data-required=\"no\" \/><\/div>\n\n<style>.kadence-column4185_a34a55-bb > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);}.kadence-column4185_a34a55-bb > .kt-inside-inner-col,.kadence-column4185_a34a55-bb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4185_a34a55-bb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4185_a34a55-bb > .kt-inside-inner-col{flex-direction:column;}.kadence-column4185_a34a55-bb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4185_a34a55-bb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4185_a34a55-bb{position:relative;}@media all and (max-width: 1024px){.kadence-column4185_a34a55-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4185_a34a55-bb > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xxs, 0.5rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4185_a34a55-bb\"><div class=\"kt-inside-inner-col\"><div class=\"kb-adv-form-field kb-field418570b899-46 wp-block-kadence-advanced-form-checkbox\"><fieldset class=\"kb-radio-check-item-wrap\" id=\"cb418570b899-46\" data-type=\"checkbox\" data-required=\"no\" ><div class=\"kb-radio-check-item\"><input class=\"kb-checkbox-style\" type=\"checkbox\"  id=\"field418570b899-46_0\" name=\"field70b899-46[]\" value=\"Quiero Wifi a bordo\"><label for=\"field418570b899-46_0\">Quiero Wifi a bordo<\/label><\/div><\/fieldset><\/div>\n\n<div class=\"kb-adv-form-field kb-field4185fde2b6-6d wp-block-kadence-advanced-form-checkbox\"><fieldset class=\"kb-radio-check-item-wrap\" id=\"cb4185fde2b6-6d\" data-type=\"checkbox\" data-required=\"no\" ><div class=\"kb-radio-check-item\"><input class=\"kb-checkbox-style\" type=\"checkbox\"  id=\"field4185fde2b6-6d_0\" name=\"fieldfde2b6-6d[]\" value=\"Quiero transporte VIP\"><label for=\"field4185fde2b6-6d_0\">Quiero transporte VIP<\/label><\/div><\/fieldset><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<div class=\"kb-adv-form-field kb-adv-form-text-type-input kb-adv-form-infield-type-input kb-field41853da181-24 wp-block-kadence-advanced-form-textarea\"><textarea name=\"field3da181-24\" id=\"field41853da181-24\" rows=\"3\"  data-label=\"Mensaje\" placeholder=\"Mensaje\" data-type=\"textarea\" class=\"kb-field kb-textarea-field\" data-required=\"yes\" required aria-required=\"true\" aria-label=\"Mensaje\"><\/textarea><\/div>\n\n<div class=\"kb-adv-form-field kb-field4185d549be-25 wp-block-kadence-advanced-form-checkbox\"><fieldset class=\"kb-radio-check-item-wrap\" id=\"cb4185d549be-25\" data-type=\"checkbox\" data-required=\"yes\" ><div class=\"kb-radio-check-item\"><input class=\"kb-checkbox-style\" type=\"checkbox\"  id=\"field4185d549be-25_0\" name=\"fieldd549be-25[]\" value=\"Acepto la &lt;a href=&quot;https:\/\/viajaenminibus.com\/es\/declaracion-de-privacidad-ue\/&quot;&gt;Pol\u00edtica de privacidad&lt;\/a&gt; \"><label for=\"field4185d549be-25_0\">Acepto la <a href=\"https:\/\/viajaenminibus.com\/es\/declaracion-de-privacidad-ue\/\">Pol\u00edtica de privacidad<\/a> <\/label><\/div><\/fieldset><\/div>\n\n<style>ul.menu .kb-submit-field .kb-btncd3a60-39.kb-button{width:initial;}.kb-submit-field.kb-fieldcd3a60-39{justify-content:flex-start;}<\/style><div class=\"kb-adv-form-field kb-submit-field kb-fieldcd3a60-39 wp-block-kadence-advanced-form-submit\"><button class=\"kb-button kt-button button kb-adv-form-submit-button kb-btncd3a60-39 kt-btn-size-standard kt-btn-width-type-full kb-btn-global-fill kt-btn-has-text-true kt-btn-has-svg-false\" type=\"submit\"><span class=\"kt-btn-inner-text\">Enviar<\/span><\/button><\/div>\n<input type=\"hidden\" name=\"_kb_adv_form_post_id\" value=\"4185\"><input type=\"hidden\" name=\"action\" value=\"kb_process_advanced_form_submit\"><input type=\"hidden\" name=\"_kb_adv_form_id\" value=\"4185-cpt-id\"><\/form><\/div><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Contacta con Nosotros: Estaremos encantados de asesorarte Datos de contacto Informaci\u00f3n adicional Preguntas frecuentes<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-2666","page","type-page","status-publish","hentry"],"taxonomy_info":[],"featured_image_src_large":false,"author_info":{"display_name":"admin","author_link":"https:\/\/viajaenminibus.com\/es\/autor\/admin\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/pages\/2666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/comments?post=2666"}],"version-history":[{"count":10,"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/pages\/2666\/revisions"}],"predecessor-version":[{"id":4691,"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/pages\/2666\/revisions\/4691"}],"wp:attachment":[{"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/media?parent=2666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}