{"id":1380,"date":"2017-03-17T12:08:02","date_gmt":"2017-03-17T12:08:02","guid":{"rendered":"http:\/\/viajaenminibus.com.mialias.net\/?p=1325"},"modified":"2026-05-25T23:44:48","modified_gmt":"2026-05-25T22:44:48","slug":"andalucia-viaje-una-experiencia","status":"publish","type":"post","link":"https:\/\/viajaenminibus.com\/es\/blog\/andalucia-viaje-una-experiencia\/","title":{"rendered":"Andaluc\u00eda, un viaje una experiencia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En Viaja en Minibus estrenamos blog.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viaja en Minibus como empresa de <strong>transportes<\/strong>, aportamos soluciones para grupos reducidos ofreciendo un <strong>servicio totalmente personalizado, puntual y flexible<\/strong> adaptado a cada necesidad concreta, t\u00fa necesidad<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s de seis d\u00e9cadas trabajando en el servicio de transportes nos avalan. Excursiones de un d\u00eda por diferentes partes de Andaluc\u00eda (<strong>C\u00f3rdoba<\/strong>, <strong>Granada,Sevilla,Ronda&#8230;)<\/strong> servicios para Bodas y Despedidas, <strong>Transfers<\/strong> (desplazamientos a hoteles, aeropuertos, etc\u2026), servicios a empresas (ofreciendo traslados de trabajadores), transportes de <strong>equipos deportivos<\/strong> (con el espacio necesario para el transporte de material)\u2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si est\u00e1s pensando en conocer <strong>Andaluc\u00eda<\/strong> y quieres disfrutar del viaje sin ninguna preocupaci\u00f3n, ponte en contacto con nosotros, encantados te ayudaremos a planificar tu excursi\u00f3n, para que solo tengas que gozar de la experiencia de recorrer, vivir y sentir&nbsp; <a href=\"http:\/\/www.andalucia.org\/es\/\" target=\"_blank\" rel=\"noopener\">Andaluc\u00eda<\/a>.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/viajaenminibus.com\/wp-content\/uploads\/2026\/01\/alhambra-967024_960_720-300x155.jpg\" alt=\"alhambra- \" class=\"wp-image-1390\" title=\"\"><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/viajaenminibus.com\/wp-content\/uploads\/2026\/01\/Puente_Nuevo_de_Ronda-300x200.jpg\" alt=\"Puente_Nuevo_de_Ronda\" class=\"wp-image-1490\" title=\"\"><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"https:\/\/viajaenminibus.com\/wp-content\/uploads\/2026\/01\/Puente_Romano_Cordoba_Andalucia-300x201.jpg\" alt=\"puente romano\" class=\"wp-image-1491\" title=\"\"><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>En Viaja en Minibus estrenamos blog para acercarte a Andaluc\u00eda y a nuestros servicios de transporte. Ofrecemos soluciones personalizadas para excursiones, eventos, transfers, empresas y grupos deportivos. M\u00e1s de 60 a\u00f1os de experiencia nos avalan para que viajes con comodidad, puntualidad y total tranquilidad.<\/p>\n","protected":false},"author":5,"featured_media":2025,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[10,11],"tags":[],"class_list":["post-1380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-andalucia","category-excursiones"],"taxonomy_info":{"category":[{"value":10,"label":"Andalucia"},{"value":11,"label":"excursiones"}]},"featured_image_src_large":["https:\/\/viajaenminibus.com\/wp-content\/uploads\/2026\/01\/Puente_Nuevo_de_Ronda-300x200.jpg",300,200,false],"author_info":{"display_name":"Jos\u00e9 Luis Navas","author_link":"https:\/\/viajaenminibus.com\/es\/autor\/jose-luis-navas\/"},"comment_info":43,"category_info":[{"term_id":10,"name":"Andalucia","slug":"andalucia","term_group":0,"term_taxonomy_id":10,"taxonomy":"category","description":"","parent":0,"count":18,"filter":"raw","cat_ID":10,"category_count":18,"category_description":"","cat_name":"Andalucia","category_nicename":"andalucia","category_parent":0},{"term_id":11,"name":"excursiones","slug":"excursiones","term_group":0,"term_taxonomy_id":11,"taxonomy":"category","description":"","parent":0,"count":18,"filter":"raw","cat_ID":11,"category_count":18,"category_description":"","cat_name":"excursiones","category_nicename":"excursiones","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/posts\/1380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/comments?post=1380"}],"version-history":[{"count":2,"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/posts\/1380\/revisions"}],"predecessor-version":[{"id":2027,"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/posts\/1380\/revisions\/2027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/media\/2025"}],"wp:attachment":[{"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/media?parent=1380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/categories?post=1380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/viajaenminibus.com\/es\/wp-json\/wp\/v2\/tags?post=1380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}